{"id":6666,"date":"2020-06-18T15:31:10","date_gmt":"2020-06-18T18:31:10","guid":{"rendered":"https:\/\/www.gamificacao.com.br\/?p=6666"},"modified":"2024-03-10T15:41:42","modified_gmt":"2024-03-10T18:41:42","slug":"ferramentas-de-gestao","status":"publish","type":"post","link":"\/blog\/ferramentas-de-gestao\/","title":{"rendered":"Ferramentas de Gest\u00e3o: Como Elas Influenciam No Resultado"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Com a transforma\u00e7\u00e3o digital que a sociedade vem passando, \u00e9 comum questionar a maneira como gerenciar o trabalho <\/span><a href=\"\/blog\/home-office-permanente\/\"><span style=\"font-weight: 400\">home office<\/span><\/a><span style=\"font-weight: 400\">. Afinal, j\u00e1 n\u00e3o \u00e9 poss\u00edvel controlar ativamente o tempo de trabalho e intervir sempre que necess\u00e1rio. Desta forma, os gestores precisam estar preparados e munidos de recursos e <a href=\"https:\/\/blog.solides.com.br\/ferramentas-de-gestao\/\" target=\"_blank\" rel=\"nofollow noopener\">ferramentas de gest\u00e3o<\/a> que facilitem todo esse processo de transi\u00e7\u00e3o do trabalho presencial para o remoto.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Conhe\u00e7a algumas das ferramentas de gest\u00e3o dispon\u00edveis no mercado para gerenciar seus colaboradores durante a jornada <\/span><i><span style=\"font-weight: 400\">home office<\/span><\/i><span style=\"font-weight: 400\">.<\/span><\/p>\n<h2><span id=\"Ferramentas_de_gestao_de_tarefas\"><strong>Ferramentas de gest\u00e3o de tarefas<\/strong><\/span><\/h2><div id=\"toc_container\" class=\"no_bullets\"><p class=\"toc_title\">&Iacute;ndice<\/p><ul class=\"toc_list\"><li><a href=\"#Ferramentas_de_gestao_de_tarefas\"><span class=\"toc_number toc_depth_1\">1<\/span> Ferramentas de gest\u00e3o de tarefas<\/a><\/li><li><a href=\"#Ferramentas_de_gestao_de_ligacao_e_videochamada\"><span class=\"toc_number toc_depth_1\">2<\/span> Ferramentas de gest\u00e3o de liga\u00e7\u00e3o e videochamada<\/a><\/li><li><a href=\"#Ferramentas_de_gestao_para_compartilhamento_de_arquivos_e_documentos\"><span class=\"toc_number toc_depth_1\">3<\/span> Ferramentas de gest\u00e3o para compartilhamento de arquivos e documentos:<\/a><\/li><li><a href=\"#Ferramentas_de_gestao_de_produtividade\"><span class=\"toc_number toc_depth_1\">4<\/span> Ferramentas de gest\u00e3o de produtividade<\/a><\/li><\/ul><\/div>\n\n<ul>\n<li style=\"font-weight: 400\"><b>Trello:<\/b><span style=\"font-weight: 400\"> Com uma interface intuitiva e colorida, o Trello permite a organiza\u00e7\u00e3o de cada etapa de um projeto. Nele, voc\u00ea pode monitorar a sua produtividade e da sua equipe, fazer coment\u00e1rios em cada tarefa, criar lembretes, entre outros.\u00a0\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Monday<\/b><span style=\"font-weight: 400\">: Esta \u00e9 uma ferramenta mais robusta e bastante destinada \u00e0 gest\u00e3o de projetos por etapas. Enquanto o Trello \u00e9 mais simplificado em sua estrutura, o Monday \u00e9 um pouco mais complexo, por\u00e9m, mais completo tamb\u00e9m. Com ele, voc\u00ea consegue criar outros modos de visualiza\u00e7\u00e3o de tarefas, como Kanban, e, ainda, criar automa\u00e7\u00f5es para o desenvolvimento e desenrolar das tarefas realizadas e das que entram nas esteiras de produ\u00e7\u00e3o.<\/span><\/li>\n<\/ul>\n<h2><span id=\"Ferramentas_de_gestao_de_ligacao_e_videochamada\"><strong>Ferramentas de gest\u00e3o de liga\u00e7\u00e3o e videochamada<\/strong><\/span><\/h2>\n<p><span style=\"font-weight: 400\">Comunicar-se ativamente com a equipe para esclarecer d\u00favidas, repassar tarefas e feedbacks \u00e9 extremamente importante. O isolamento f\u00edsico n\u00e3o precisa ser transferido para o escrit\u00f3rio virtual, logo, a comunica\u00e7\u00e3o e colabora\u00e7\u00e3o s\u00e3o essenciais em momentos como esse. Essas ferramentas podem te ajudar nessa quest\u00e3o:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><b>Zoom<\/b><span style=\"font-weight: 400\">: Tem coisas que s\u00f3 podem ser resolvidas com uma boa e velha reuni\u00e3o. No trabalho home office tamb\u00e9m \u00e9 assim, e com o Zoom \u00e9 poss\u00edvel realizar videoconfer\u00eancia com uma ou mais pessoas. Al\u00e9m disso, voc\u00ea pode gravar um v\u00eddeo da reuni\u00e3o e compartilhar com toda a sua equipe.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Slack:<\/b><span style=\"font-weight: 400\"> \u00e9 uma plataforma de comunica\u00e7\u00e3o interna e funciona como um ambiente de trabalho virtual, no qual, voc\u00ea se comunica com a sua equipe em grupo ou com cada funcion\u00e1rio, separadamente. Voc\u00ea tamb\u00e9m pode personalizar canais de comunica\u00e7\u00e3o de acordo com um tema, cliente, assunto ou projeto.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: center\"><figure class=\"wp-block-embed wp-block-embed-youtube is-type-video is-provider-youtube epyt-figure\"><div class=\"wp-block-embed__wrapper\"><div  id=\"_ytid_17634\"  width=\"800\" height=\"450\"  data-origwidth=\"800\" data-origheight=\"450\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/26b9LTJ1M_Q?enablejsapi=1&autoplay=0&cc_load_policy=0&iv_load_policy=1&loop=0&modestbranding=0&fs=1&playsinline=0&controls=1&color=red&cc_lang_pref=&rel=0&autohide=2&theme=dark&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\" alt=\"YouTube player\" src=\"https:\/\/i.ytimg.com\/vi\/26b9LTJ1M_Q\/maxresdefault.jpg\" title=\"\"><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div><\/figure><\/p>\n<h2><span id=\"Ferramentas_de_gestao_para_compartilhamento_de_arquivos_e_documentos\"><strong>Ferramentas de gest\u00e3o para compartilhamento de arquivos e documentos:<\/strong><\/span><\/h2>\n<ul>\n<li><b>GoogleDrive:<span style=\"font-weight: 400\"> a suite do Google oferece o Drive, uma ferramenta onde \u00e9 poss\u00edvel visualizar arquivos e documentos de maneira facilitada e sem a necessidade de ter os programas como Excel, Word e Powerpoint instalados nos computadores. Al\u00e9m disso, todos permitem feedbacks e cocria\u00e7\u00e3o em tempo real.\u00a0<\/span><\/b><\/li>\n<\/ul>\n<ul>\n<li>Dropbox <span style=\"font-weight: 400\">assim como o GoogleDrive, tamb\u00e9m \u00e9 uma das ferramentas mais conhecidas para armazenamento de arquivos e documentos \u2013 e tamb\u00e9m possui vers\u00f5es gratuitas de at\u00e9 15GB.<\/span><\/li>\n<\/ul>\n<h2><span id=\"Ferramentas_de_gestao_de_produtividade\"><strong>Ferramentas de gest\u00e3o de produtividade<\/strong><\/span><\/h2>\n<p><span style=\"font-weight: 400\">Se a sua necessidade enquanto gestor \u00e9 acompanhar a produtividade do seu time em tempo real, com relat\u00f3rios e uma tecnologia de <\/span><i><span style=\"font-weight: 400\">machine learning<\/span><\/i><span style=\"font-weight: 400\"> e intelig\u00eancia artificial capaz de dar um<\/span><i><span style=\"font-weight: 400\"> boost<\/span><\/i><span style=\"font-weight: 400\"> nos seus resultados, conhe\u00e7a a <\/span><a href=\"http:\/\/www.gamefic.me\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">Gamefic<\/span><\/a><span style=\"font-weight: 400\"> &#8211; uma plataforma de gerenciamento baseada no <a href=\"https:\/\/www.gamefic.me\/blog\/o-que-e-gamificacao-o-guia-definitivo\/\" target=\"_blank\" rel=\"noopener\">conceito de gamifica\u00e7\u00e3o<\/a> para promover maior envolvimento e participa\u00e7\u00e3o da equipe.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Este \u00e9 um novo modelo de gest\u00e3o de equipes \u00e0 dist\u00e2ncia, capaz de apresentar uma vis\u00e3o ampla e completa do desempenho do time, ao mesmo tempo em que aumenta o engajamento e estimula a produtividade.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Atrav\u00e9s do <\/span><i><span style=\"font-weight: 400\">machine learning<\/span><\/i><span style=\"font-weight: 400\">, a ferramenta analisa o perfil do usu\u00e1rio, sendo capaz de entender seus padr\u00f5es de utiliza\u00e7\u00e3o. Dessa forma, o sistema colhe informa\u00e7\u00f5es importantes para conseguir auxiliar gestores em suas tomadas de decis\u00e3o. Com base nos dados colhidos, o sistema consegue coloc\u00e1-los em uso de forma inteligente atrav\u00e9s de previs\u00f5es e recomenda\u00e7\u00f5es autom\u00e1ticas e personalizadas, a fim de auxiliar na tomada de decis\u00f5es e impulsionar seus resultados.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Treinamentos podem ser disponibilizados para toda a equipe de maneira simples e pr\u00e1tica. Reduzindo custos e o tempo gasto com a produ\u00e7\u00e3o de treinamentos criados do zero, \u00e9 poss\u00edvel garantir sua efic\u00e1cia mesmo \u00e0 dist\u00e2ncia.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Uma das ferramentas de gest\u00e3o, a Gamefic, tamb\u00e9m conta com um canal de comunica\u00e7\u00e3o onde \u00e9 poss\u00edvel fazer posts, coment\u00e1rios, curtir e compartilhar conte\u00fados. Um canal de informa\u00e7\u00f5es que mant\u00e9m todos atualizados quanto ao que acontece na empresa e incentiva a participa\u00e7\u00e3o e o engajamento entre colaboradores.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Al\u00e9m disso, sua interface l\u00fadica e interativa permite feedbacks instant\u00e2neos possibilitando que l\u00edderes e todos os colaboradores estejam sempre em sintonia.<\/span><\/p>\n<p><span style=\"font-weight: 400\">J\u00e1 pensou em adotar alguma dessas ferramentas de gest\u00e3o? Esteja preparado para o futuro dos modelos de trabalho e gest\u00e3o. Adote uma tecnologia persuasiva no seu neg\u00f3cio e sinta a diferen\u00e7a no comportamento e resultado dos colaboradores. Venha para a <\/span><span style=\"font-weight: 400\">Gamefic<\/span><span style=\"font-weight: 400\">.<\/span><\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/cultura.gamefic.me\/ebook-gamificacao-inovacao-e-engajamento\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-6897\" src=\"http:\/\/root.gamefic.me\/wp-content\/uploads\/sites\/18\/2020\/08\/banner-blog-ebook-gamificacao-13-08-20-1.jpg\" alt=\"Ebook Gamifica\u00e7\u00e3o: Engajamento e inova\u00e7\u00e3o\" width=\"419\" height=\"109\" srcset=\"\/wp-content\/uploads\/sites\/18\/2020\/08\/banner-blog-ebook-gamificacao-13-08-20-1.jpg 768w, \/wp-content\/uploads\/sites\/18\/2020\/08\/banner-blog-ebook-gamificacao-13-08-20-1-300x78.jpg 300w\" sizes=\"(max-width: 419px) 100vw, 419px\" title=\"\"><\/a><figure class=\"wp-block-embed wp-block-embed-youtube is-type-video is-provider-youtube epyt-figure\"><div class=\"wp-block-embed__wrapper\"><div  id=\"_ytid_94751\"  width=\"800\" height=\"450\"  data-origwidth=\"800\" data-origheight=\"450\"  data-relstop=\"1\" data-facadesrc=\"https:\/\/www.youtube.com\/embed\/MfumjofYrUM?enablejsapi=1&autoplay=0&cc_load_policy=0&iv_load_policy=1&loop=0&modestbranding=0&fs=1&playsinline=0&controls=1&color=red&cc_lang_pref=&rel=0&autohide=2&theme=dark&\" class=\"__youtube_prefs__ epyt-facade no-lazyload\" data-epautoplay=\"1\" ><img data-spai-excluded=\"true\" class=\"epyt-facade-poster skip-lazy\" loading=\"lazy\" alt=\"YouTube player\" src=\"https:\/\/i.ytimg.com\/vi\/MfumjofYrUM\/maxresdefault.jpg\" title=\"\"><button class=\"epyt-facade-play\" aria-label=\"Play\"><svg data-no-lazy=\"1\" height=\"100%\" version=\"1.1\" viewBox=\"0 0 68 48\" width=\"100%\"><path class=\"ytp-large-play-button-bg\" d=\"M66.52,7.74c-0.78-2.93-2.49-5.41-5.42-6.19C55.79,.13,34,0,34,0S12.21,.13,6.9,1.55 C3.97,2.33,2.27,4.81,1.48,7.74C0.06,13.05,0,24,0,24s0.06,10.95,1.48,16.26c0.78,2.93,2.49,5.41,5.42,6.19 C12.21,47.87,34,48,34,48s21.79-0.13,27.1-1.55c2.93-0.78,4.64-3.26,5.42-6.19C67.94,34.95,68,24,68,24S67.94,13.05,66.52,7.74z\" fill=\"#f00\"><\/path><path d=\"M 45,24 27,14 27,34\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><\/div><\/figure><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a transforma\u00e7\u00e3o digital que a sociedade vem passando, \u00e9 comum questionar a maneira como gerenciar o trabalho home office. Afinal, j\u00e1 n\u00e3o \u00e9 poss\u00edvel controlar ativamente o tempo de trabalho e intervir sempre que necess\u00e1rio. Desta forma, os gestores precisam estar preparados e munidos de recursos e ferramentas de gest\u00e3o que facilitem todo esse&hellip; <a class=\"more-link\" href=\"\/blog\/ferramentas-de-gestao\/\">Continuar lendo <span class=\"screen-reader-text\">Ferramentas de Gest\u00e3o: Como Elas Influenciam No Resultado<\/span><\/a><\/p>\n","protected":false},"author":10,"featured_media":6667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[136,43,121,48,113],"_links":{"self":[{"href":"\/blog\/wp-json\/wp\/v2\/posts\/6666"}],"collection":[{"href":"\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/comments?post=6666"}],"version-history":[{"count":7,"href":"\/blog\/wp-json\/wp\/v2\/posts\/6666\/revisions"}],"predecessor-version":[{"id":12608,"href":"\/blog\/wp-json\/wp\/v2\/posts\/6666\/revisions\/12608"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/media\/6667"}],"wp:attachment":[{"href":"\/blog\/wp-json\/wp\/v2\/media?parent=6666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/categories?post=6666"},{"taxonomy":"post_tag","embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/tags?post=6666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}