{"id":7408,"date":"2020-11-05T07:10:23","date_gmt":"2020-11-05T10:10:23","guid":{"rendered":"https:\/\/www.gamificacao.com.br\/?p=7408"},"modified":"2023-01-23T14:43:32","modified_gmt":"2023-01-23T17:43:32","slug":"produtividade","status":"publish","type":"post","link":"\/blog\/produtividade\/","title":{"rendered":"Produtividade: Os Principais Vil\u00f5es Que Voc\u00ea Deve Evitar"},"content":{"rendered":"<h2><span id=\"Produtividade_pessoal\">Produtividade pessoal<\/span><\/h2><div id=\"toc_container\" class=\"no_bullets\"><p class=\"toc_title\">&Iacute;ndice<\/p><ul class=\"toc_list\"><li><a href=\"#Produtividade_pessoal\"><span class=\"toc_number toc_depth_1\">1<\/span> Produtividade pessoal<\/a><\/li><li><a href=\"#O_que_e_produtividade\"><span class=\"toc_number toc_depth_1\">2<\/span> O que \u00e9 produtividade?<\/a><ul><li><a href=\"#Entretanto_produtividade_e_diferente_de_ser_produtivo\"><span class=\"toc_number toc_depth_2\">2.1<\/span> Entretanto, produtividade \u00e9 diferente de ser produtivo<\/a><\/li><\/ul><\/li><li><a href=\"#Mas_e_ai_quais_sao_os_inimigos_da_produtividade\"><span class=\"toc_number toc_depth_1\">3<\/span> Mas e a\u00ed, quais s\u00e3o os inimigos da produtividade?<\/a><ul><li><a href=\"#Procrastinacao\"><span class=\"toc_number toc_depth_2\">3.1<\/span> Procrastina\u00e7\u00e3o<\/a><\/li><li><a href=\"#Falta_de_planejamento\"><span class=\"toc_number toc_depth_2\">3.2<\/span> Falta de planejamento<\/a><\/li><li><a href=\"#Abracar_o_mundo_com_as_pernas\"><span class=\"toc_number toc_depth_2\">3.3<\/span> Abra\u00e7ar o mundo com as pernas<\/a><\/li><li><a href=\"#Foco_e_concentracao\"><span class=\"toc_number toc_depth_2\">3.4<\/span> Foco e concentra\u00e7\u00e3o<\/a><\/li><\/ul><\/li><li><a href=\"#Busque_ser_produtivo_e_nao_um_robo\"><span class=\"toc_number toc_depth_1\">4<\/span> Busque ser produtivo, e n\u00e3o um rob\u00f4<\/a><\/li><\/ul><\/div>\n\n<p><span style=\"font-weight: 400\">\u201cHoje meu dia precisa ser mais produtivo!\u201d. <\/span><span style=\"font-weight: 400\">Quem nunca falou isso, que atire a primeira pedra. <\/span><span style=\"font-weight: 400\">\u00c9 natural que a produtividade seja afetada em algum momento. Afinal, o ser humano \u00e9 dotado de sentimentos e motiva\u00e7\u00f5es que podem interferir no desempenho de atividades.<\/span><\/p>\n<p><span style=\"font-weight: 400\">O importante \u00e9 ter aten\u00e7\u00e3o aos sinais da presen\u00e7a dos inimigos da produtividade. E consequentemente, exercitar a mente para evitar os bloqueios que interrompem o bom desenvolvimento das atividades.<\/span><\/p>\n<h2><span id=\"O_que_e_produtividade\"><span style=\"font-weight: 400\">O que \u00e9 produtividade?<\/span><\/span><\/h2>\n<p><span style=\"font-weight: 400\">A <a href=\"\/blog\/gestao-do-tempo-e-produtividade\/\">produtividade<\/a> pode ser definida como a capacidade da m\u00e1xima produ\u00e7\u00e3o, com uso m\u00ednimo de recursos, no menor tempo poss\u00edvel. Ela est\u00e1 diretamente relacionada com o planejamento, organiza\u00e7\u00e3o de tarefas e gest\u00e3o de tempo.\u00a0<\/span><\/p>\n<h3><span id=\"Entretanto_produtividade_e_diferente_de_ser_produtivo\"><span style=\"font-weight: 400\">Entretanto, produtividade \u00e9 diferente de ser produtivo<\/span><\/span><\/h3>\n<p><span style=\"font-weight: 400\"><a href=\"https:\/\/www.tecnicon.com.br\/blog\/554-Ser_produtivo_ou_estar_ocupado_Qual_a_diferenca_\" target=\"_blank\" rel=\"nofollow noopener\">Ser produtivo<\/a> est\u00e1 longe de ser aquela pessoa el\u00e9trica que realiza diversas tarefas ao mesmo tempo sem prestar aten\u00e7\u00e3o em nenhuma delas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Na verdade, ser produtivo \u00e9 saber organizar e entender cada uma das tarefas, colocando em ordem de prioridade e necessidade. \u00c9 seguir um cronograma pensado para executar atividades com qualidade.<\/span><\/p>\n<h2><span id=\"Mas_e_ai_quais_sao_os_inimigos_da_produtividade\"><span style=\"font-weight: 400\">Mas e a\u00ed, quais s\u00e3o os inimigos da produtividade?<\/span><\/span><\/h2>\n<p><span style=\"font-weight: 400\">Ser produtivo \u00e9 importante. Seja no trabalho, nos estudos ou nas tarefas de casa, sentir-se produtivo traz<\/span><a href=\"https:\/\/www.gamefic.me\/blog\/reconhecimentos-e-recompensas\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400\">recompensas<\/span><\/a><span style=\"font-weight: 400\"> para o bem-estar e a autoestima, al\u00e9m de ser um motivador natural para execu\u00e7\u00e3o de novas tarefas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Por isso, \u00e9 preciso evitar ao m\u00e1ximo alguns vil\u00f5es que acabam com a produtividade e fazem voc\u00ea chegar ao fim do dia com o pensamento \u201ceu n\u00e3o fiz nada do que precisava hoje\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Entre os principais inimigos da produtividade, podemos destacar:<\/span><\/p>\n<h3><span id=\"Procrastinacao\"><span style=\"font-weight: 400\">Procrastina\u00e7\u00e3o<\/span><\/span><\/h3>\n<p><span style=\"font-weight: 400\">A <a href=\"https:\/\/ead.univali.br\/blog\/procrastinacao\" target=\"_blank\" rel=\"nofollow noopener\">procrastina\u00e7\u00e3o<\/a> \u00e9 o que mais afeta o desempenho individual e de equipes em uma organiza\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Deixar para depois tarefas aparentemente chatas ou sem urg\u00eancia de conclus\u00e3o parece ser o caminho mais f\u00e1cil. O problema \u00e9 que, quando chegar o momento de realizar a tarefa, o tempo ser\u00e1 curto e a motiva\u00e7\u00e3o menor ainda.\u00a0<\/span><\/p>\n<h3><span id=\"Falta_de_planejamento\"><span style=\"font-weight: 400\">Falta de planejamento<\/span><\/span><\/h3>\n<p><span style=\"font-weight: 400\">Executar tarefas sem qualquer tipo de planejamento tamb\u00e9m afeta a produtividade. N\u00e3o ter um plano de a\u00e7\u00e3o traz consequ\u00eancias como: ac\u00famulo de tarefas, falta de prioridade nas atividades, torna o trabalho cansativo e repetitivo e diminui o rendimento.<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u00c9 fundamental separar os primeiros minutos do dia para \u201corganizar a casa\u201d antes de colocar a m\u00e3o na massa.<\/span><\/p>\n<h3><span id=\"Abracar_o_mundo_com_as_pernas\"><span style=\"font-weight: 400\">Abra\u00e7ar o mundo com as pernas<\/span><\/span><\/h3>\n<p><span style=\"font-weight: 400\">Esse ditado serve para exemplificar aquela pessoa multitarefas. Ter v\u00e1rias habilidades \u00e9 bom, sim! Isso \u00e9 ineg\u00e1vel. Entretanto, \u00e9 preciso executar uma atividade por vez.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Ali\u00e1s, ao tentar dividir a aten\u00e7\u00e3o entre v\u00e1rias atividades ao mesmo tempo, \u00e9 bem capaz que ao fim do dia nenhuma seja entregue com qualidade.<\/span><\/p>\n<h3><span id=\"Foco_e_concentracao\"><span style=\"font-weight: 400\">Foco e concentra\u00e7\u00e3o<\/span><\/span><\/h3>\n<p><span style=\"font-weight: 400\">A capacidade de concentra\u00e7\u00e3o \u00e9 diretamente afetada pela quantidade de informa\u00e7\u00f5es que recebemos a todo momento. Dispositivos m\u00f3veis, TVs, Internet e tantas outras coisas disputam a nossa aten\u00e7\u00e3o a cada segundo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nesse caso, a produtividade agradece \u00e0queles que conseguem manter o foco pelo tempo necess\u00e1rio da execu\u00e7\u00e3o de uma tarefa.\u00a0<\/span><\/p>\n<h2><span id=\"Busque_ser_produtivo_e_nao_um_robo\"><span style=\"font-weight: 400\">Busque ser produtivo, e n\u00e3o um rob\u00f4<\/span><\/span><\/h2>\n<p><span style=\"font-weight: 400\">Como foi dito no in\u00edcio deste texto, \u00e9 natural que o ser humano passe por momentos de baixa produtividade.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Primeiramente, \u00e9 preciso aceitar que isso pode acontecer. Ap\u00f3s isso, treinar a mente para que ela consiga buscar novos caminhos para a produtividade quando as vias conhecidas estejam bloqueadas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Veja mais dicas de produtividade e gest\u00e3o de tempo no<\/span><a href=\"https:\/\/www.gamefic.me\/blog\/\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400\">nosso blog<\/span><\/a><span style=\"font-weight: 400\"> e conhe\u00e7a mais a<\/span><a href=\"https:\/\/www.gamefic.me\/\" target=\"_blank\" rel=\"noopener\"> <span style=\"font-weight: 400\">Gamefic<\/span><\/a><span style=\"font-weight: 400\">.\u00a0\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Produtividade pessoal&Iacute;ndice1 Produtividade pessoal2 O que \u00e9 produtividade?2.1 Entretanto, produtividade \u00e9 diferente de ser produtivo3 Mas e a\u00ed, quais s\u00e3o os inimigos da produtividade?3.1 Procrastina\u00e7\u00e3o3.2 Falta de planejamento3.3 Abra\u00e7ar o mundo com as pernas3.4 Foco e concentra\u00e7\u00e3o4 Busque ser produtivo, e n\u00e3o um rob\u00f4 \u201cHoje meu dia precisa ser mais produtivo!\u201d. Quem nunca falou isso,&hellip; <a class=\"more-link\" href=\"\/blog\/produtividade\/\">Continuar lendo <span class=\"screen-reader-text\">Produtividade: Os Principais Vil\u00f5es Que Voc\u00ea Deve Evitar<\/span><\/a><\/p>\n","protected":false},"author":10,"featured_media":7411,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[235],"tags":[237,43,15,236,240,238,239,35],"_links":{"self":[{"href":"\/blog\/wp-json\/wp\/v2\/posts\/7408"}],"collection":[{"href":"\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/comments?post=7408"}],"version-history":[{"count":3,"href":"\/blog\/wp-json\/wp\/v2\/posts\/7408\/revisions"}],"predecessor-version":[{"id":10161,"href":"\/blog\/wp-json\/wp\/v2\/posts\/7408\/revisions\/10161"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/media\/7411"}],"wp:attachment":[{"href":"\/blog\/wp-json\/wp\/v2\/media?parent=7408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/categories?post=7408"},{"taxonomy":"post_tag","embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/tags?post=7408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}