{"id":7414,"date":"2020-11-06T07:10:43","date_gmt":"2020-11-06T10:10:43","guid":{"rendered":"https:\/\/www.gamificacao.com.br\/?p=7414"},"modified":"2024-03-10T18:56:17","modified_gmt":"2024-03-10T21:56:17","slug":"saude-mental-do-colaborador","status":"publish","type":"post","link":"\/blog\/saude-mental-do-colaborador\/","title":{"rendered":"Sa\u00fade Mental do Colaborador &#8211; Pr\u00e1ticas Que As Empresas Devem Adotar"},"content":{"rendered":"<h2><span id=\"Saude_Mental_do_Colaborador\"><strong>Sa\u00fade Mental do Colaborador<\/strong><\/span><\/h2><div id=\"toc_container\" class=\"no_bullets\"><p class=\"toc_title\">&Iacute;ndice<\/p><ul class=\"toc_list\"><li><a href=\"#Saude_Mental_do_Colaborador\"><span class=\"toc_number toc_depth_1\">1<\/span> Sa\u00fade Mental do Colaborador<\/a><\/li><li><a href=\"#O_que_fazer_para_manter_a_saude_mental_do_colaborador_durante_o_isolamento_social\"><span class=\"toc_number toc_depth_1\">2<\/span> O que fazer para manter a sa\u00fade mental do colaborador durante o isolamento social?<\/a><ul><li><ul><li><a href=\"#Crie_um_espaco_profissional\"><span class=\"toc_number toc_depth_3\">2.0.1<\/span> Crie um espa\u00e7o profissional<\/a><\/li><li><a href=\"#Mantenha_um_cronograma_regular\"><span class=\"toc_number toc_depth_3\">2.0.2<\/span> Mantenha um cronograma regular<\/a><\/li><li><a href=\"#Fique_conectado\"><span class=\"toc_number toc_depth_3\">2.0.3<\/span> Fique conectado<\/a><\/li><li><a href=\"#Pratique_exercicios_e_mantenha-se_ativo\"><span class=\"toc_number toc_depth_3\">2.0.4<\/span> Pratique exerc\u00edcios e mantenha-se ativo<\/a><\/li><li><a href=\"#Mantenha-se_informado\"><span class=\"toc_number toc_depth_3\">2.0.5<\/span> Mantenha-se informado<\/a><\/li><li><a href=\"#Distraia_e_redirecione\"><span class=\"toc_number toc_depth_3\">2.0.6<\/span> Distraia e redirecione<\/a><\/li><\/ul><\/li><\/ul><\/li><li><a href=\"#O_que_os_gestores_podem_fazer_para_apoiar_seus_colaboradores\"><span class=\"toc_number toc_depth_1\">3<\/span> O que os gestores podem fazer para apoiar seus colaboradores?<\/a><ul><li><ul><li><a href=\"#Mostre_empatia_e_esteja_disponivel\"><span class=\"toc_number toc_depth_3\">3.0.1<\/span> Mostre empatia e esteja dispon\u00edvel<\/a><\/li><li><a href=\"#Fique_conectado_com_as_ferramentas_de_comunicacao_e_reuniao\"><span class=\"toc_number toc_depth_3\">3.0.2<\/span> Fique conectado com as ferramentas de comunica\u00e7\u00e3o e reuni\u00e3o<\/a><\/li><li><a href=\"#Reconheca_o_impacto_do_isolamento_e_da_solidao\"><span class=\"toc_number toc_depth_3\">3.0.3<\/span> Reconhe\u00e7a o impacto do isolamento e da solid\u00e3o<\/a><\/li><li><a href=\"#Incentive_o_treinamento_online\"><span class=\"toc_number toc_depth_3\">3.0.4<\/span> Incentive o treinamento online<\/a><\/li><li><a href=\"#Mantenha_a_comunicacao\"><span class=\"toc_number toc_depth_3\">3.0.5<\/span> Mantenha a comunica\u00e7\u00e3o\u00a0<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/div>\n\n<p><span style=\"font-weight: 400\">O isolamento social causado pelo coronav\u00edrus nos trouxe uma nova realidade para o nosso trabalho e para nossas rela\u00e7\u00f5es e a sa\u00fade mental do colaborador virou um tema de ainda maior import\u00e2ncia neste cen\u00e1rio. O sentimento de incerteza, ansiedade, frustra\u00e7\u00e3o, medo, t\u00e9dio, s\u00e3o alguns dos sentimentos que as pessoas t\u00eam experimentado ao praticar o distanciamento social para ajudar no controle da dissemina\u00e7\u00e3o do coronav\u00edrus (COVID-19).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Quando o trabalho e a casa se tornam um s\u00f3 lugar, pode ser dif\u00edcil manter os limites entre os dois. Problemas de se desligar do trabalho podem levar a <a href=\"https:\/\/www.gamefic.me\/blog\/comunicacao-interna\" target=\"_blank\" rel=\"noopener\">relacionamentos pessoais<\/a> diminu\u00eddos e perda de tempo que normalmente envolve atividades de lazer ou relaxamento.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Outro detalhe que deve ser considerado, durante o home office, \u00e9 que o isolamento do local de trabalho tamb\u00e9m pode significar o isolamento de informa\u00e7\u00f5es importantes e culturas positivas da empresa. Isso n\u00e3o apenas limitar\u00e1 a efici\u00eancia, mas tamb\u00e9m pode comprometer a sensa\u00e7\u00e3o de seguran\u00e7a no emprego.<\/span><\/p>\n<h2><span id=\"O_que_fazer_para_manter_a_saude_mental_do_colaborador_durante_o_isolamento_social\"><span style=\"font-weight: 400\">O que fazer para manter a sa\u00fade mental do colaborador durante o isolamento social?<\/span><\/span><\/h2>\n<p><span style=\"font-weight: 400\">Como empregador, \u00e9 seu dever proteger o bem-estar dos seus colaboradores, sem esquecer do seu pr\u00f3prio bem-estar. Com isso em mente, o que podemos fazer para garantir que nosso ambiente de trabalho seja favor\u00e1vel \u00e0 sa\u00fade e \u00e0 produtividade?<\/span><\/p>\n<h4><span id=\"Crie_um_espaco_profissional\"><strong>Crie um espa\u00e7o profissional<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Goste ou n\u00e3o, voc\u00ea n\u00e3o ir\u00e1 trabalhar bem sentado na cama com a TV ligada em segundo plano. Crie um espa\u00e7o de trabalho profissional, com cadeira e mesa que n\u00e3o prejudiquem sua postura. Voc\u00ea tamb\u00e9m n\u00e3o precisa gastar dinheiro, mas \u00e9 importante separar o trabalho e a casa, mesmo que seja dedicando um canto da sala para isso.<\/span><\/p>\n<h4><span id=\"Mantenha_um_cronograma_regular\"><strong>Mantenha um cronograma regular<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Crie e mantenha uma rotina e um cronograma. Configure um espa\u00e7o designado para voc\u00ea e cada membro da fam\u00edlia trabalhar e aprender. N\u00e3o se esque\u00e7a de incluir pausas peri\u00f3dicas para recarga em sua programa\u00e7\u00e3o.<\/span><\/p>\n<h4><span id=\"Fique_conectado\"><strong>Fique conectado<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Fique conectado com a fam\u00edlia, amigos e os colegas de trabalho usando tecnologias como FaceTime, Skype, Google Hangout e outras op\u00e7\u00f5es de v\u00eddeo chamadas. Fale sobre seus medos e preocupa\u00e7\u00f5es com pessoas que confia. Provavelmente, eles est\u00e3o se sentindo da mesma maneira.<\/span><\/p>\n<h4><span id=\"Pratique_exercicios_e_mantenha-se_ativo\"><strong>Pratique exerc\u00edcios e mantenha-se ativo<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Isso n\u00e3o \u00e9 bom apenas para sua sa\u00fade f\u00edsica, mas tamb\u00e9m para sua sa\u00fade mental. Periodicamente, levante-se e ande pela casa. Caminhadas, corridas, alongamentos, o que funcionar melhor para voc\u00ea para reduzir o estresse e aumentar as endorfinas. Fa\u00e7a exerc\u00edcios em casa ou na rua mantendo o distanciamento social e seguindo as medidas de prote\u00e7\u00e3o.<\/span><\/p>\n<h4><span id=\"Mantenha-se_informado\"><strong>Mantenha-se informado<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Conhecimento \u00e9 poder, e \u00e9 bom manter-se atualizado sobre o progresso feito no combate ao v\u00edrus. Mantenha-se informado sobre as \u00faltimas atualiza\u00e7\u00f5es de fontes confi\u00e1veis. Mas \u00e9 importante limitar o consumo dessas informa\u00e7\u00f5es. Evite a exposi\u00e7\u00e3o cont\u00ednua a not\u00edcias, m\u00eddia e m\u00eddias sociais que podem aumentar a ansiedade, o estresse ou o p\u00e2nico.<\/span><\/p>\n<h4><span id=\"Distraia_e_redirecione\"><strong>Distraia e redirecione<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Envolva-se em atividades que beneficiem o seu bem-estar, proporcionem alegria e o distraiam dos desafios existentes. Isso pode incluir medita\u00e7\u00e3o e yoga, muitas vezes oferecidos gratuitamente online. Voc\u00ea tamb\u00e9m pode desfrutar de um di\u00e1rio, leitura, projetos de arte, cozinhar novas receitas, fazer exerc\u00edcios de respira\u00e7\u00e3o, ouvir um podcast ou m\u00fasica calmante.<\/span><\/p>\n<h2><span id=\"O_que_os_gestores_podem_fazer_para_apoiar_seus_colaboradores\"><span style=\"font-weight: 400\">O que os gestores podem fazer para apoiar seus colaboradores?<\/span><\/span><\/h2>\n<p><span style=\"font-weight: 400\">Com muitas organiza\u00e7\u00f5es exigindo que os funcion\u00e1rios permane\u00e7am fora do escrit\u00f3rio, \u00e9 mais importante do que nunca incentivar e facilitar a <a href=\"https:\/\/www.gamefic.me\/blog\/comunicacao-empresarial-interna\/\" target=\"_blank\" rel=\"noopener\">comunica\u00e7\u00e3o<\/a> regular com os funcion\u00e1rios.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Aqui est\u00e3o algumas dicas para gerentes e profissionais de recursos humanos no apoio aos funcion\u00e1rios para se manterem conectados ao local de trabalho e uns aos outros:<\/span><\/p>\n<h4><span id=\"Mostre_empatia_e_esteja_disponivel\"><strong>Mostre empatia e esteja dispon\u00edvel<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Entenda que os funcion\u00e1rios provavelmente est\u00e3o se sentindo sobrecarregados e ansiosos com as circunst\u00e2ncias relacionadas ao v\u00edrus. Coloque-se \u00e0 disposi\u00e7\u00e3o de sua equipe para falar sobre medos, responder perguntas e tranquiliz\u00e1-los sobre o trabalho e outras quest\u00f5es que possam surgir.<\/span><\/p>\n<h4><span id=\"Fique_conectado_com_as_ferramentas_de_comunicacao_e_reuniao\"><strong>Fique conectado com as ferramentas de comunica\u00e7\u00e3o e reuni\u00e3o<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Use as op\u00e7\u00f5es de reuni\u00e3o virtual com v\u00eddeo, como Zoom ou JoinMe, para check-ins regulares e para permitir que as equipes se conectem &#8220;cara a cara&#8221;.<\/span><\/p>\n<h4><span id=\"Reconheca_o_impacto_do_isolamento_e_da_solidao\"><strong>Reconhe\u00e7a o impacto do isolamento e da solid\u00e3o<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Trabalhar remotamente pode fazer com que as pessoas se sintam isoladas, tornando mais importante checar rotineiramente com sua equipe, n\u00e3o apenas sobre o produto de trabalho, mas tamb\u00e9m como est\u00e3o se saindo. A solid\u00e3o pode levar \u00e0 depress\u00e3o e outros problemas de sa\u00fade mental. Esteja ciente das mudan\u00e7as significativas que voc\u00ea pode ver na personalidade ou no produto de trabalho de seu membro da equipe, porque pode ser um sinal de que uma pessoa est\u00e1 lutando.<\/span><\/p>\n<h4><span id=\"Incentive_o_treinamento_online\"><strong>Incentive o treinamento online<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Este \u00e9 um \u00f3timo momento para incentivar os funcion\u00e1rios a aprimorarem suas habilidades com o treinamento online. Tamb\u00e9m \u00e9 uma boa distra\u00e7\u00e3o se concentrar no aprendizado em vez de se preocupar com outras quest\u00f5es. Encontre treinamentos online e novas oportunidades de aprendizagem para recomendar aos funcion\u00e1rios.<\/span><\/p>\n<h4><span id=\"Mantenha_a_comunicacao\"><strong>Mantenha a comunica\u00e7\u00e3o\u00a0<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400\">Certifique-se de que voc\u00ea e sua equipe estejam por perto. O Facetime ou o Skype podem ajudar com isso se voc\u00ea estiver trabalhando remotamente. H\u00e1 uma grande responsabilidade para as empresas serem mais inclusivas em suas reuni\u00f5es, ent\u00e3o comunique-se diariamente, se fa\u00e7a presente e mostre que est\u00e1 dispon\u00edvel.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Aproveite para usar ferramentas de gest\u00e3o para melhorar a colabora\u00e7\u00e3o e manter o fluxo de trabalho organizado e sob controle. Os gestores tamb\u00e9m podem aproveitar as vantagens de uma equipe virtual e manter a produtividade sob controle com a <\/span><a href=\"https:\/\/www.gamefic.me\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">Gamefic<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Use uma ferramenta que permite registrar informa\u00e7\u00f5es, organizar o trabalho e engajar a equipe de forma mais colaborativa. Experimente gratuitamente <\/span><a href=\"https:\/\/www.gamefic.me\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">aqui<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sa\u00fade Mental do Colaborador&Iacute;ndice1 Sa\u00fade Mental do Colaborador2 O que fazer para manter a sa\u00fade mental do colaborador durante o isolamento social?2.0.1 Crie um espa\u00e7o profissional2.0.2 Mantenha um cronograma regular2.0.3 Fique conectado2.0.4 Pratique exerc\u00edcios e mantenha-se ativo2.0.5 Mantenha-se informado2.0.6 Distraia e redirecione3 O que os gestores podem fazer para apoiar seus colaboradores?3.0.1 Mostre empatia e&hellip; <a class=\"more-link\" href=\"\/blog\/saude-mental-do-colaborador\/\">Continuar lendo <span class=\"screen-reader-text\">Sa\u00fade Mental do Colaborador &#8211; Pr\u00e1ticas Que As Empresas Devem Adotar<\/span><\/a><\/p>\n","protected":false},"author":10,"featured_media":7415,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,5],"tags":[43,15,241,188],"_links":{"self":[{"href":"\/blog\/wp-json\/wp\/v2\/posts\/7414"}],"collection":[{"href":"\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/comments?post=7414"}],"version-history":[{"count":5,"href":"\/blog\/wp-json\/wp\/v2\/posts\/7414\/revisions"}],"predecessor-version":[{"id":12787,"href":"\/blog\/wp-json\/wp\/v2\/posts\/7414\/revisions\/12787"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/media\/7415"}],"wp:attachment":[{"href":"\/blog\/wp-json\/wp\/v2\/media?parent=7414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/categories?post=7414"},{"taxonomy":"post_tag","embeddable":true,"href":"\/blog\/wp-json\/wp\/v2\/tags?post=7414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}